{"id":572,"date":"2023-05-26T16:50:19","date_gmt":"2023-05-26T14:50:19","guid":{"rendered":"http:\/\/www.nettunomisano.com\/?page_id=572"},"modified":"2025-02-13T10:21:58","modified_gmt":"2025-02-13T09:21:58","slug":"gallery","status":"publish","type":"page","link":"https:\/\/www.nettunomisano.com\/en\/gallery\/","title":{"rendered":"Gallery"},"content":{"rendered":"<section class=\"wao-blocks-container container mb-5\"\n\t\t>\n    \n<div class=\"wao-blocks-row row\" >\n    \n\n<div class=\"col-12 col-md-12 p-5\"\n     \n\t \n\t>\n        \n\n<div class=\"breadcrumb-block mb-4\"\n    >\n    <div class=\"font-weight-breadcrumbs text-uppercase\">\n        <a href=\"https:\/\/www.nettunomisano.com\/en\" rel=\"nofollow\" title=\"Home\">Home ><\/a>\n        Gallery    <\/div>\n<\/div>\n\n\n<h1 class=\"wp-block-heading text-uppercase\">Gallery<\/h1>\n\n\n\n<h2 class=\"wp-block-heading text-square text-secondary mb-4\">A preview of your holiday\u00a0<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ti aspettiamo in hotel, ma intanto scopri gli ambienti e\u00a0 le camere della tua prossima vacanza attraverso la nostra gallery.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<div class=\"wao-blocks-gallery-v1\">\n\t<div class=\"row p-0 m-0 l--gallery-grid\"><div class=\"col-6 l--height-3 l--p-gall\"><div style=\"height: 100%; background-image: url(https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2023\/05\/gallery-nettuno-001-1024x783.jpg)\">\n\t\t\t<a href=\"https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2023\/05\/gallery-nettuno-001-1024x783.jpg\" rel=\"ilightBox\" class=\"d-block h-100\" title=\"Apri la galleria\"><\/a><\/div><\/div><div class=\"col-6 p-x-0\"><div class=\"row\"><div class=\"col-6 l--height-1 l--p-gall\"><div style=\"height: 100%; background-image: url(https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2025\/02\/gallery-nettuno-05.jpg)\">\n\t\t\t<a href=\"https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2025\/02\/gallery-nettuno-05.jpg\" rel=\"ilightBox\" class=\"d-block h-100\" title=\"Apri la galleria\"><\/a><\/div><\/div><div class=\"col-6 l--height-1 l--p-gall\"><div style=\"height: 100%; background-image: url(https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2025\/02\/gallery-nettuno-01.jpg)\">\n\t\t\t<a href=\"https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2025\/02\/gallery-nettuno-01.jpg\" rel=\"ilightBox\" class=\"d-block h-100\" title=\"Apri la galleria\"><\/a><\/div><\/div><div class=\"col-6 l--height-1 l--p-gall\"><div style=\"height: 100%; background-image: url(https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2025\/02\/gallery-nettuno-07.jpg)\">\n\t\t\t<a href=\"https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2025\/02\/gallery-nettuno-07.jpg\" rel=\"ilightBox\" class=\"d-block h-100\" title=\"Apri la galleria\"><\/a><\/div><\/div><div class=\"col-6 l--height-1 l--p-gall\"><div style=\"height: 100%; background-image: url(https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2025\/02\/gallery-nettuno-04-683x1024.jpg)\">\n\t\t\t<a href=\"https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2025\/02\/gallery-nettuno-04-683x1024.jpg\" rel=\"ilightBox\" class=\"d-block h-100\" title=\"Apri la galleria\"><\/a><\/div><\/div><\/div><\/div><div class=\"col-6 p-x-0\"><div class=\"row\"><div class=\"col-6 l--height-1 l--p-gall\"><div style=\"height: 100%; background-image: url(https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2025\/02\/gallery-nettuno-06-683x1024.jpg)\">\n\t\t\t<a href=\"https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2025\/02\/gallery-nettuno-06-683x1024.jpg\" rel=\"ilightBox\" class=\"d-block h-100\" title=\"Apri la galleria\"><\/a><\/div><\/div><div class=\"col-6 l--height-1 l--p-gall\"><div style=\"height: 100%; background-image: url(https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2023\/05\/gallery-nettuno-009.jpg)\">\n\t\t\t<a href=\"https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2023\/05\/gallery-nettuno-009.jpg\" rel=\"ilightBox\" class=\"d-block h-100\" title=\"Apri la galleria\"><\/a><\/div><\/div><div class=\"col-6 l--height-1 l--p-gall\"><div style=\"height: 100%; background-image: url(https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2023\/05\/gallery-nettuno-013.jpg)\">\n\t\t\t<a href=\"https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2023\/05\/gallery-nettuno-013.jpg\" rel=\"ilightBox\" class=\"d-block h-100\" title=\"Apri la galleria\"><\/a><\/div><\/div><div class=\"col-6 l--height-1 l--p-gall\"><div style=\"height: 100%; background-image: url(https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2023\/05\/gallery-nettuno-015.jpg)\">\n\t\t\t<a href=\"https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2023\/05\/gallery-nettuno-015.jpg\" rel=\"ilightBox\" class=\"d-block h-100\" title=\"Apri la galleria\"><\/a><\/div><\/div><\/div><\/div><div class=\"col-6 l--height-3 l--p-gall\"><div style=\"height: 100%; background-image: url(https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2023\/05\/gallery-nettuno-014.jpg)\">\n\t\t\t<a href=\"https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2023\/05\/gallery-nettuno-014.jpg\" rel=\"ilightBox\" class=\"d-block h-100\" title=\"Apri la galleria\"><\/a><\/div><\/div>\n\t\t\t<div class=\"col-5 l--height-2 l--p-gall\">\n\t\t\t<div style=\"height: 100%; background-image:url(https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2025\/02\/gallery-nettuno-03.jpg)\"><a href=\"https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2025\/02\/gallery-nettuno-03.jpg\" rel=\"ilightBox\" class=\"d-block h-100\" title=\"Apri la galleria\"><\/a><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-3 l--height-2 l--p-gall\">\n\t\t\t<div style=\"height: 100%; background-image:url(https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2025\/02\/gallery-nettuno-02.jpg)\"><a href=\"https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2025\/02\/gallery-nettuno-02.jpg\" rel=\"ilightBox\" class=\"d-block h-100\" title=\"Apri la galleria\"><\/a><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-4 l--height-2 l--p-gall\">\n\t\t\t<div style=\"height: 100%; background-image:url(https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2023\/05\/gallery-nettuno-011.jpg)\"><a href=\"https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2023\/05\/gallery-nettuno-011.jpg\" rel=\"ilightBox\" class=\"d-block h-100\" title=\"Apri la galleria\"><\/a><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-3 l--height-2 l--p-gall\">\n\t\t\t<div style=\"height: 100%; background-image:url(https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2023\/05\/gallery-nettuno-012.jpg)\"><a href=\"https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2023\/05\/gallery-nettuno-012.jpg\" rel=\"ilightBox\" class=\"d-block h-100\" title=\"Apri la galleria\"><\/a><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-4 l--height-2 l--p-gall\">\n\t\t\t<div style=\"height: 100%; background-image:url(https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2023\/05\/gallery-nettuno-016-1024x1024.jpg)\"><a href=\"https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2023\/05\/gallery-nettuno-016-1024x1024.jpg\" rel=\"ilightBox\" class=\"d-block h-100\" title=\"Apri la galleria\"><\/a><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-5 l--height-2 l--p-gall\">\n\t\t\t<div style=\"height: 100%; background-image:url(https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2023\/05\/gallery-nettuno-017-1024x1024.jpg)\"><a href=\"https:\/\/www.nettunomisano.com\/wp-content\/uploads\/2023\/05\/gallery-nettuno-017-1024x1024.jpg\" rel=\"ilightBox\" class=\"d-block h-100\" title=\"Apri la galleria\"><\/a><\/div>\n\t\t\t<\/div><\/div>\n  <\/div>\n    <\/div>\n<\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-572","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.nettunomisano.com\/en\/wp-json\/wp\/v2\/pages\/572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nettunomisano.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.nettunomisano.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.nettunomisano.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nettunomisano.com\/en\/wp-json\/wp\/v2\/comments?post=572"}],"version-history":[{"count":5,"href":"https:\/\/www.nettunomisano.com\/en\/wp-json\/wp\/v2\/pages\/572\/revisions"}],"predecessor-version":[{"id":1457,"href":"https:\/\/www.nettunomisano.com\/en\/wp-json\/wp\/v2\/pages\/572\/revisions\/1457"}],"wp:attachment":[{"href":"https:\/\/www.nettunomisano.com\/en\/wp-json\/wp\/v2\/media?parent=572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}